<br />
<b>Warning</b>:  Constant ABSPATH already defined in <b>/home/clients/1fe8eda1db8c250ae979846675665306/web/wp-config.php</b> on line <b>92</b><br />
{"id":1420,"date":"2019-05-10T14:16:59","date_gmt":"2019-05-10T12:16:59","guid":{"rendered":"https:\/\/www.hublemania.ch\/?p=1420"},"modified":"2020-09-03T23:37:50","modified_gmt":"2020-09-03T21:37:50","slug":"lemania-depliant-de-presentation","status":"publish","type":"post","link":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/","title":{"rendered":"lemania &#8211; D\u00e9pliant de pr\u00e9sentation"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;3.22.3&#8243; custom_margin=&#8220;0px||28px|&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;0px||0px|&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220;][et_pb_fullwidth_slider show_arrows=&#8220;off&#8220; show_pagination=&#8220;off&#8220; module_class=&#8220;internal-slider&#8220; _builder_version=&#8220;3.16&#8243; background_image=&#8220;https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/banner_bleu_1920x350-2.jpg&#8220; custom_padding=&#8220;130px||130px|&#8220; custom_css_slide_title=&#8220;color:rgba(255, 0, 0, 0.09);&#8220; button_text_size__hover_enabled=&#8220;off&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_text_color__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_border_width__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_border_color__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;off&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_border_radius__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;off&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_letter_spacing__hover_enabled=&#8220;off&#8220; button_one_letter_spacing__hover_enabled=&#8220;off&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_bg_color__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;off&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220;][et_pb_slide heading=&#8220;documentation&#8220; use_bg_overlay=&#8220;off&#8220; use_text_overlay=&#8220;off&#8220; _builder_version=&#8220;3.16&#8243; background_color=&#8220;#7EBEC5&#8243; button_on_hover=&#8220;on&#8220; button_text_size__hover_enabled=&#8220;off&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_text_color__hover_enabled=&#8220;off&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_border_width__hover_enabled=&#8220;off&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_border_color__hover_enabled=&#8220;off&#8220; button_one_border_color__hover_enabled=&#8220;off&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_border_radius__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover_enabled=&#8220;off&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_letter_spacing__hover_enabled=&#8220;off&#8220; button_one_letter_spacing__hover_enabled=&#8220;off&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_bg_color__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover_enabled=&#8220;off&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220;][\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; make_equal=&#8220;on&#8220; specialty=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; padding_top_1=&#8220;0px&#8220; padding_top_2=&#8220;0px&#8220; _builder_version=&#8220;3.22.3&#8243; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px|0px|28px|0px&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;0px|0px|7px|0px&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/08\/arrow25.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; disabled_on=&#8220;on||&#8220; admin_label=&#8220;Image > (gris)&#8220; module_class=&#8220;iconleft&#8220; _builder_version=&#8220;3.23&#8243; custom_margin=&#8220;|-50px||&#8220;]&nbsp;<br \/>\n[\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; specialty_columns=&#8220;3&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner custom_padding_last_edited=&#8220;on|phone&#8220; admin_label=&#8220;Ligne&#8220; _builder_version=&#8220;3.25&#8243; max_width=&#8220;95%&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px|22.2%|0px|&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;0px|0px|0px|&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Texte titre&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#666666&#8243; header_font_size=&#8220;20px&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||0px|&#8220;]<\/p>\n<h1>lemania &#8211; D\u00e9pliant de pr\u00e9sentation<\/h1>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; make_equal=&#8220;on&#8220; specialty=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; padding_top_1=&#8220;0px&#8220; padding_top_2=&#8220;0px&#8220; _builder_version=&#8220;3.22.3&#8243; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||28px|&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;0px||7px|&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; specialty_columns=&#8220;3&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;3.25&#8243; max_width=&#8220;95%&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px|22.2%|0px|&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;0px|0px|0px|&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.0.11&#8243; custom_margin=&#8220;|||&#8220;]<\/p>\n<p>La vie des gens change, le monde du travail \u00e9volue \u2013 et le domaine de la pr\u00e9voyance, logiquement, n\u2019est pas en reste, avec des d\u00e9fis d\u00e9mographiques, \u00e9conomiques et politiques consid\u00e9rables. Quelles solutions faut-il proposer aujourd\u2019hui, pour permettre aux assur\u00e9s de planifier leur avenir financier de fa\u00e7on optimale, <em>a fortiori<\/em> lorsqu\u2019ils sont cadres ou dirigeants d\u2019entreprise\u00a0? Ce questionnement est \u00e0 l\u2019origine du projet lemania \u2013 pension hub, qui se donne pour mission de r\u00e9unir, en une m\u00eame plateforme, les solutions de pr\u00e9voyance les plus dynamiques, et les plus \u00e0 m\u00eame de r\u00e9pondre aux besoins des b\u00e9n\u00e9ficiaires exigeants d\u2019aujourd\u2019hui.<\/p>\n<p>T\u00e9l\u00e9charger le d\u00e9pliant de pr\u00e9sentation de<em> lemania &#8211; pension hub<\/em> (format PDF) (mise \u00e0 jour en cours,)<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner admin_label=&#8220;Ligne&#8220; _builder_version=&#8220;3.25&#8243;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_post_nav in_same_term=&#8220;off&#8220; prev_text=&#8220;Article pr\u00e9c\u00e9dent&#8220; next_text=&#8220;Article suivant&#8220; _builder_version=&#8220;3.15&#8243;]&nbsp;<br \/>\n[\/et_pb_post_nav][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; make_equal=&#8220;on&#8220; specialty=&#8220;on&#8220; _builder_version=&#8220;3.22.3&#8243; background_image=&#8220;https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/banner_bleu_1920x350-2.jpg&#8220; custom_margin=&#8220;0px||28px|&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;0px||7px|&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;54px|||&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/08\/arrow25white.png&#8220; align=&#8220;right&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; disabled_on=&#8220;on||&#8220; admin_label=&#8220;Image > (blanc)&#8220; module_class=&#8220;iconleft&#8220; _builder_version=&#8220;3.23&#8243; custom_margin=&#8220;|-50px||&#8220;]&nbsp;<br \/>\n[\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; specialty_columns=&#8220;3&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner custom_padding_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;3.25&#8243; max_width=&#8220;95%&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_padding=&#8220;|22.2%||&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;|0px||&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|0px||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; module_class=&#8220;lienspecial&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; custom_margin=&#8220;|||&#8220;]<\/p>\n<h4>Suivez notre actualit\u00e9<\/h4>\n<p>Notre politique de gouvernance accorde de l&#8217;importance \u00e0 la transparence et \u00e0 l&#8217;information. La plateforme lemania \u2013 pension hub est un projet dynamique en constante \u00e9volution. Le projet de lemania &#8211; pension hub est en constante \u00e9volution, son actualit\u00e9 est riche. Nous vous proposons de la suivre via ce site, sur lequel vous pouvez d\u00e9couvrir nos derni\u00e8res nouvelles. Vous avez \u00e9galement la possibilit\u00e9 de vous inscrire \u00e0 notre newsletter \u00e9lectronique.<\/p>\n<p><a href=\"https:\/\/www.hublemania.ch\/portrait\/actualite\/\">Lire nos derni\u00e8res nouvelles<\/a><br \/>\n[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelles solutions faut-il proposer aujourd\u2019hui pour permettre aux assur\u00e9s de planifier leur avenir financier de fa\u00e7on optimale, a fortiori lorsqu\u2019ils sont cadres ou dirigeants d\u2019entreprise ? Ce questionnement est \u00e0 l\u2019origine du projet lemania \u2013 pension hub, qui se donne pour mission de r\u00e9unir, en une m\u00eame plateforme, les solutions de pr\u00e9voyance les plus dynamiques et les plus \u00e0 m\u00eame de r\u00e9pondre aux besoins des b\u00e9n\u00e9ficiaires exigeants d\u2019aujourd\u2019hui.<\/p>\n","protected":false},"author":7,"featured_media":1433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-1420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania<\/title>\n<meta name=\"description\" content=\"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d&#039;auteur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d&#039;auteur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/\" \/>\n<meta property=\"og:site_name\" content=\"Lemania- Pension Fund\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T12:16:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-03T21:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Michellod\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Michellod\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/\"},\"author\":{\"name\":\"Alexandre Michellod\",\"@id\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/#\\\/schema\\\/person\\\/0a1d07e5e98955a66c6d16f7b3cb5557\"},\"headline\":\"lemania &#8211; D\u00e9pliant de pr\u00e9sentation\",\"datePublished\":\"2019-05-10T12:16:59+00:00\",\"dateModified\":\"2020-09-03T21:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/\"},\"wordCount\":1241,\"image\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hublemania.ch\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/image-depliant-opt.jpg\",\"articleSection\":[\"Documentation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/\",\"url\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/\",\"name\":\"lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hublemania.ch\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/image-depliant-opt.jpg\",\"datePublished\":\"2019-05-10T12:16:59+00:00\",\"dateModified\":\"2020-09-03T21:37:50+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/#\\\/schema\\\/person\\\/0a1d07e5e98955a66c6d16f7b3cb5557\"},\"description\":\"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d'auteur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hublemania.ch\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/image-depliant-opt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hublemania.ch\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/image-depliant-opt.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hublemania.ch\\\/de\\\/lemania-depliant-de-presentation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"startseite\",\"item\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lemania &#8211; D\u00e9pliant de pr\u00e9sentation\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/#website\",\"url\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/\",\"name\":\"Lemania- Pension Fund\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.hublemania.ch\\\/de\\\/#\\\/schema\\\/person\\\/0a1d07e5e98955a66c6d16f7b3cb5557\",\"name\":\"Alexandre Michellod\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g\",\"caption\":\"Alexandre Michellod\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania","description":"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d'auteur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/","og_locale":"de_DE","og_type":"article","og_title":"lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania","og_description":"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d'auteur.","og_url":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/","og_site_name":"Lemania- Pension Fund","article_published_time":"2019-05-10T12:16:59+00:00","article_modified_time":"2020-09-03T21:37:50+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","type":"image\/jpeg"}],"author":"Alexandre Michellod","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Alexandre Michellod","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#article","isPartOf":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/"},"author":{"name":"Alexandre Michellod","@id":"http:\/\/www.hublemania.ch\/de\/#\/schema\/person\/0a1d07e5e98955a66c6d16f7b3cb5557"},"headline":"lemania &#8211; D\u00e9pliant de pr\u00e9sentation","datePublished":"2019-05-10T12:16:59+00:00","dateModified":"2020-09-03T21:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/"},"wordCount":1241,"image":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","articleSection":["Documentation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/","url":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/","name":"lemania - D\u00e9pliant de pr\u00e9sentation - Mieux conna\u00eetre lemania","isPartOf":{"@id":"http:\/\/www.hublemania.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#primaryimage"},"image":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","datePublished":"2019-05-10T12:16:59+00:00","dateModified":"2020-09-03T21:37:50+00:00","author":{"@id":"http:\/\/www.hublemania.ch\/de\/#\/schema\/person\/0a1d07e5e98955a66c6d16f7b3cb5557"},"description":"Le d\u00e9pliant de pr\u00e9sentation de lemania - pension hub, trois volets, au format PDF t\u00e9l\u00e9chargeable en ligne. Soumis \u00e0 des droits d'auteur.","breadcrumb":{"@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#primaryimage","url":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","contentUrl":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/www.hublemania.ch\/de\/lemania-depliant-de-presentation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"startseite","item":"http:\/\/www.hublemania.ch\/de\/"},{"@type":"ListItem","position":2,"name":"lemania &#8211; D\u00e9pliant de pr\u00e9sentation"}]},{"@type":"WebSite","@id":"http:\/\/www.hublemania.ch\/de\/#website","url":"http:\/\/www.hublemania.ch\/de\/","name":"Lemania- Pension Fund","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.hublemania.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/www.hublemania.ch\/de\/#\/schema\/person\/0a1d07e5e98955a66c6d16f7b3cb5557","name":"Alexandre Michellod","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/47a44e524708de59cd12cf9350b9cedf558cb04e565ee85df767d48c04972564?s=96&d=mm&r=g","caption":"Alexandre Michellod"}}]}},"jetpack_featured_media_url":"https:\/\/www.hublemania.ch\/wp-content\/uploads\/2018\/09\/image-depliant-opt.jpg","_links":{"self":[{"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/posts\/1420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/comments?post=1420"}],"version-history":[{"count":0,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/posts\/1420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/media\/1433"}],"wp:attachment":[{"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/media?parent=1420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/categories?post=1420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hublemania.ch\/de\/wp-json\/wp\/v2\/tags?post=1420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}